{"id":6596,"date":"2021-11-05T13:54:00","date_gmt":"2021-11-05T12:54:00","guid":{"rendered":"https:\/\/www.novatris.uha.fr\/?p=6596"},"modified":"2021-11-05T16:28:35","modified_gmt":"2021-11-05T15:28:35","slug":"prix-universitaire-franco-allemand-grand-est-2022","status":"publish","type":"post","link":"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/","title":{"rendered":"Prix Universitaire Franco-Allemand Grand Est 2022"},"content":{"rendered":"<p>Dans le cadre de la collaboration universitaire franco-allemande des universit\u00e9s de la <a href=\"https:\/\/www.grandest.fr\/\" target=\"_blank\" rel=\"noopener\">R\u00e9gion Grand Est<\/a>, l\u2019<a href=\"https:\/\/www.uha.fr\/fr\/index.html\" target=\"_blank\" rel=\"noopener\">Universit\u00e9 de Haute-Alsace<\/a> (UHA) participe \u00e0 l\u2019organisation du <strong>Prix Universitaire Franco-Allemand Grand Est (PUFAGE) 2022<\/strong> qu\u2019elle cofinance \u00e0 travers <strong>NovaTris<\/strong>.<\/p>\n<h3><strong>Le PUFAGE 2022<\/strong><\/h3>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6631 alignright\" src=\"http:\/\/www.novatris.uha.fr\/wp-content\/uploads\/2021\/11\/Photo_PUFAGE-300x212.jpg\" alt=\"Image d'illustration PUFAGE 2022\" width=\"367\" height=\"259\" srcset=\"http:\/\/www.novatris.uha.fr\/wp-content\/uploads\/2021\/11\/Photo_PUFAGE-300x212.jpg 300w, http:\/\/www.novatris.uha.fr\/wp-content\/uploads\/2021\/11\/Photo_PUFAGE-1024x725.jpg 1024w, http:\/\/www.novatris.uha.fr\/wp-content\/uploads\/2021\/11\/Photo_PUFAGE-768x543.jpg 768w, http:\/\/www.novatris.uha.fr\/wp-content\/uploads\/2021\/11\/Photo_PUFAGE-1536x1087.jpg 1536w, http:\/\/www.novatris.uha.fr\/wp-content\/uploads\/2021\/11\/Photo_PUFAGE-2048x1449.jpg 2048w\" sizes=\"auto, (max-width: 367px) 100vw, 367px\" \/><\/h3>\n<p>Le PUFAGE 2022, Prix Charles de Villers, vise \u00e0 r\u00e9compenser et valoriser l\u2019excellence des travaux d\u2019\u00e9tudiants des fili\u00e8res franco-allemandes des <strong>cinq universit\u00e9s<\/strong> de la R\u00e9gion Grand Est, \u00e0 savoir\u00a0l\u2019UHA, l\u2019<a href=\"https:\/\/www.univ-lorraine.fr\/\" target=\"_blank\" rel=\"noopener\">Universit\u00e9 de Lorraine<\/a>, l\u2019<a href=\"https:\/\/www.univ-reims.fr\/\" target=\"_blank\" rel=\"noopener\">Universit\u00e9 de Reims-Champagne Ardennes<\/a>, l\u2019<a href=\"https:\/\/www.unistra.fr\/\" target=\"_blank\" rel=\"noopener\">Universit\u00e9 de Strasbourg<\/a> et l\u2019<a href=\"https:\/\/www.utt.fr\/\" target=\"_blank\" rel=\"noopener\">Universit\u00e9 de technologie de Troyes<\/a>.<\/p>\n<p>Soutenant et mettant en lumi\u00e8re l&rsquo;offre de formation franco-allemande dans la r\u00e9gion, ce prix participe \u00e9galement au d\u00e9veloppement d\u2019une <strong>coop\u00e9ration<\/strong> toujours plus forte <strong>entre l\u2019Allemagne et la France<\/strong>, plus particuli\u00e8rement entre les <strong>trois L\u00e4nder frontaliers<\/strong> &#8211; la Sarre, la Rh\u00e9nanie-Palatinat et le Bade-Wurtemberg &#8211; et la R\u00e9gion Grand Est.<\/p>\n<h3><strong>Les cat\u00e9gories <\/strong><\/h3>\n<p>Cinq cat\u00e9gories diff\u00e9rentes sont propos\u00e9es\u00a0:<\/p>\n<div class=\"su-list\" style=\"margin-left:0px\">\n<ul>\n<li><i class=\"sui sui-chevron-right\" style=\"color:#333\"><\/i> prix pour la meilleure th\u00e8se en \u00ab\u00a0Sciences Humaines et Sociales, Lettres et Langues, Management et Droit\u00a0\u00bb\u00a0;<\/li>\n<li><i class=\"sui sui-chevron-right\" style=\"color:#333\"><\/i> prix pour la meilleure th\u00e8se en \u00ab Sciences et Techniques-Ing\u00e9nierie \u00bb ;<\/li>\n<li><i class=\"sui sui-chevron-right\" style=\"color:#333\"><\/i> prix pour le meilleur m\u00e9moire de master en \u00ab\u00a0Sciences Humaines et Sociales, Lettres et Langues, Management et Droit\u00a0\u00bb\u00a0;<\/li>\n<li><i class=\"sui sui-chevron-right\" style=\"color:#333\"><\/i> prix pour le meilleur m\u00e9moire de master en \u00ab Sciences et Techniques-Ing\u00e9nierie \u00bb ;<\/li>\n<li><i class=\"sui sui-chevron-right\" style=\"color:#333\"><\/i> prix pour un m\u00e9moire bas\u00e9 sur un projet franco-allemand collectif.<\/li>\n<\/ul>\n<\/div>\n<p>D\u2019une valeur de 500 euros chacun, ces prix seront <strong>d\u00e9cern\u00e9s le 21 janvier 2022<\/strong> sur le site de Metz de l\u2019Universit\u00e9 de Lorraine en pr\u00e9sence des partenaires co-organisateurs.<\/p>\n<h3><strong>Les conditions de candidature<\/strong><\/h3>\n<p>Pour candidater \u00e0 l\u2019un de ces prix, il est n\u00e9cessaire de remplir les conditions suivantes :<\/p>\n<div class=\"su-list\" style=\"margin-left:0px\">\n<ul>\n<li><i class=\"sui sui-check\" style=\"color:#333\"><\/i> \u00eatre inscrit dans l\u2019une des cinq universit\u00e9s de la R\u00e9gion Grand Est\u00a0;<\/li>\n<li><i class=\"sui sui-check\" style=\"color:#333\"><\/i> \u00eatre \u00e9tudiant en master ou \u00e9quivalent pour les prix m\u00e9moires de master, \u00eatre \u00e9tudiant en licence pour le Prix Projet ou \u00eatre titulaire de doctorat pour les prix de th\u00e8se\u00a0;<\/li>\n<li><i class=\"sui sui-check\" style=\"color:#333\"><\/i> Avoir \u00e9crit un m\u00e9moire ou une th\u00e8se r\u00e9dig\u00e9s en allemand, fran\u00e7ais ou en anglais portant sur une th\u00e9matique en lien avec le franco-allemand.<\/li>\n<\/ul>\n<\/div>\n<p>Les dossiers de candidatures doivent \u00eatre <strong>d\u00e9pos\u00e9s au plus tard le 8 d\u00e9cembre 2021<\/strong> \u00e0 minuit.<\/p>\n<a href=\"http:\/\/www.novatris.uha.fr\/wp-content\/uploads\/2021\/11\/Dossier-candidature-PUFAGE-22.pdf\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#004996;border-color:#003b78;border-radius:6px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#4d80b6;border-radius:6px;text-shadow:none\"><i class=\"sui sui-file-text\" style=\"font-size:14px;color:#FFFFFF\"><\/i> Formulaire de candidature<\/span><\/a>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\">Cr\u00e9dit Photo : NovaTris<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre de la collaboration universitaire franco-allemande des universit\u00e9s de la R\u00e9gion Grand Est, l\u2019Universit\u00e9 de Haute-Alsace (UHA) participe \u00e0 l\u2019organisation du Prix Universitaire Franco-Allemand Grand Est (PUFAGE) 2022 qu\u2019elle cofinance \u00e0 travers NovaTris. Le PUFAGE 2022 Le PUFAGE 2022, Prix Charles de Villers, vise \u00e0 r\u00e9compenser et valoriser l\u2019excellence des travaux d\u2019\u00e9tudiants des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6631,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Prix Universitaire Franco-Allemand Grand Est 2022 - NovaTris, centre de comp\u00e9tences transfrontali\u00e8res | Universit\u00e9 de Haute-Alsace<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prix Universitaire Franco-Allemand Grand Est 2022 - NovaTris, centre de comp\u00e9tences transfrontali\u00e8res | Universit\u00e9 de Haute-Alsace\" \/>\n<meta property=\"og:description\" content=\"Dans le cadre de la collaboration universitaire franco-allemande des universit\u00e9s de la R\u00e9gion Grand Est, l\u2019Universit\u00e9 de Haute-Alsace (UHA) participe \u00e0 l\u2019organisation du Prix Universitaire Franco-Allemand Grand Est (PUFAGE) 2022 qu\u2019elle cofinance \u00e0 travers NovaTris. Le PUFAGE 2022 Le PUFAGE 2022, Prix Charles de Villers, vise \u00e0 r\u00e9compenser et valoriser l\u2019excellence des travaux d\u2019\u00e9tudiants des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"NovaTris, centre de comp\u00e9tences transfrontali\u00e8res | Universit\u00e9 de Haute-Alsace\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-05T12:54:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-05T15:28:35+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.novatris.uha.fr\/wp-content\/uploads\/2021\/11\/Photo_PUFAGE-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1812\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmaster@uha.fr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmaster@uha.fr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/\",\"url\":\"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/\",\"name\":\"Prix Universitaire Franco-Allemand Grand Est 2022 - NovaTris, centre de comp\u00e9tences transfrontali\u00e8res | Universit\u00e9 de Haute-Alsace\",\"isPartOf\":{\"@id\":\"http:\/\/www.novatris.uha.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.novatris.uha.fr\/wp-content\/uploads\/2021\/11\/Photo_PUFAGE-scaled.jpg\",\"datePublished\":\"2021-11-05T12:54:00+00:00\",\"dateModified\":\"2021-11-05T15:28:35+00:00\",\"author\":{\"@id\":\"http:\/\/www.novatris.uha.fr\/#\/schema\/person\/8aec3138a2e34db9ede91fe59ca322c8\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/#primaryimage\",\"url\":\"http:\/\/www.novatris.uha.fr\/wp-content\/uploads\/2021\/11\/Photo_PUFAGE-scaled.jpg\",\"contentUrl\":\"http:\/\/www.novatris.uha.fr\/wp-content\/uploads\/2021\/11\/Photo_PUFAGE-scaled.jpg\",\"width\":2560,\"height\":1812,\"caption\":\"Image d'illustration PUFAGE 2022\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\/\/www.novatris.uha.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prix Universitaire Franco-Allemand Grand Est 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.novatris.uha.fr\/#website\",\"url\":\"http:\/\/www.novatris.uha.fr\/\",\"name\":\"NovaTris, centre de comp\u00e9tences transfrontali\u00e8res | Universit\u00e9 de Haute-Alsace\",\"description\":\"Campus Illberg | Universit\u00e9 de Haute-Alsace\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.novatris.uha.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/www.novatris.uha.fr\/#\/schema\/person\/8aec3138a2e34db9ede91fe59ca322c8\",\"name\":\"webmaster@uha.fr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\/\/www.novatris.uha.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7ae9c9b105a64214a8aa9fbd2c7d306cf0a8dc064d0aecf25fd00cb3af1c5089?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7ae9c9b105a64214a8aa9fbd2c7d306cf0a8dc064d0aecf25fd00cb3af1c5089?s=96&d=mm&r=g\",\"caption\":\"webmaster@uha.fr\"},\"url\":\"http:\/\/www.novatris.uha.fr\/index.php\/author\/webmasteruha-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prix Universitaire Franco-Allemand Grand Est 2022 - NovaTris, centre de comp\u00e9tences transfrontali\u00e8res | Universit\u00e9 de Haute-Alsace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/","og_locale":"fr_FR","og_type":"article","og_title":"Prix Universitaire Franco-Allemand Grand Est 2022 - NovaTris, centre de comp\u00e9tences transfrontali\u00e8res | Universit\u00e9 de Haute-Alsace","og_description":"Dans le cadre de la collaboration universitaire franco-allemande des universit\u00e9s de la R\u00e9gion Grand Est, l\u2019Universit\u00e9 de Haute-Alsace (UHA) participe \u00e0 l\u2019organisation du Prix Universitaire Franco-Allemand Grand Est (PUFAGE) 2022 qu\u2019elle cofinance \u00e0 travers NovaTris. Le PUFAGE 2022 Le PUFAGE 2022, Prix Charles de Villers, vise \u00e0 r\u00e9compenser et valoriser l\u2019excellence des travaux d\u2019\u00e9tudiants des [&hellip;]","og_url":"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/","og_site_name":"NovaTris, centre de comp\u00e9tences transfrontali\u00e8res | Universit\u00e9 de Haute-Alsace","article_published_time":"2021-11-05T12:54:00+00:00","article_modified_time":"2021-11-05T15:28:35+00:00","og_image":[{"width":2560,"height":1812,"url":"http:\/\/www.novatris.uha.fr\/wp-content\/uploads\/2021\/11\/Photo_PUFAGE-scaled.jpg","type":"image\/jpeg"}],"author":"webmaster@uha.fr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"webmaster@uha.fr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/","url":"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/","name":"Prix Universitaire Franco-Allemand Grand Est 2022 - NovaTris, centre de comp\u00e9tences transfrontali\u00e8res | Universit\u00e9 de Haute-Alsace","isPartOf":{"@id":"http:\/\/www.novatris.uha.fr\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/#primaryimage"},"image":{"@id":"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/#primaryimage"},"thumbnailUrl":"http:\/\/www.novatris.uha.fr\/wp-content\/uploads\/2021\/11\/Photo_PUFAGE-scaled.jpg","datePublished":"2021-11-05T12:54:00+00:00","dateModified":"2021-11-05T15:28:35+00:00","author":{"@id":"http:\/\/www.novatris.uha.fr\/#\/schema\/person\/8aec3138a2e34db9ede91fe59ca322c8"},"breadcrumb":{"@id":"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/#primaryimage","url":"http:\/\/www.novatris.uha.fr\/wp-content\/uploads\/2021\/11\/Photo_PUFAGE-scaled.jpg","contentUrl":"http:\/\/www.novatris.uha.fr\/wp-content\/uploads\/2021\/11\/Photo_PUFAGE-scaled.jpg","width":2560,"height":1812,"caption":"Image d'illustration PUFAGE 2022"},{"@type":"BreadcrumbList","@id":"http:\/\/www.novatris.uha.fr\/index.php\/prix-universitaire-franco-allemand-grand-est-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/www.novatris.uha.fr\/"},{"@type":"ListItem","position":2,"name":"Prix Universitaire Franco-Allemand Grand Est 2022"}]},{"@type":"WebSite","@id":"http:\/\/www.novatris.uha.fr\/#website","url":"http:\/\/www.novatris.uha.fr\/","name":"NovaTris, centre de comp\u00e9tences transfrontali\u00e8res | Universit\u00e9 de Haute-Alsace","description":"Campus Illberg | Universit\u00e9 de Haute-Alsace","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.novatris.uha.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/www.novatris.uha.fr\/#\/schema\/person\/8aec3138a2e34db9ede91fe59ca322c8","name":"webmaster@uha.fr","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/www.novatris.uha.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7ae9c9b105a64214a8aa9fbd2c7d306cf0a8dc064d0aecf25fd00cb3af1c5089?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ae9c9b105a64214a8aa9fbd2c7d306cf0a8dc064d0aecf25fd00cb3af1c5089?s=96&d=mm&r=g","caption":"webmaster@uha.fr"},"url":"http:\/\/www.novatris.uha.fr\/index.php\/author\/webmasteruha-fr\/"}]}},"_links":{"self":[{"href":"http:\/\/www.novatris.uha.fr\/index.php\/wp-json\/wp\/v2\/posts\/6596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.novatris.uha.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.novatris.uha.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.novatris.uha.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.novatris.uha.fr\/index.php\/wp-json\/wp\/v2\/comments?post=6596"}],"version-history":[{"count":28,"href":"http:\/\/www.novatris.uha.fr\/index.php\/wp-json\/wp\/v2\/posts\/6596\/revisions"}],"predecessor-version":[{"id":6646,"href":"http:\/\/www.novatris.uha.fr\/index.php\/wp-json\/wp\/v2\/posts\/6596\/revisions\/6646"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.novatris.uha.fr\/index.php\/wp-json\/wp\/v2\/media\/6631"}],"wp:attachment":[{"href":"http:\/\/www.novatris.uha.fr\/index.php\/wp-json\/wp\/v2\/media?parent=6596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.novatris.uha.fr\/index.php\/wp-json\/wp\/v2\/categories?post=6596"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.novatris.uha.fr\/index.php\/wp-json\/wp\/v2\/tags?post=6596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}